{"id":1419,"date":"2012-08-29T16:26:49","date_gmt":"2012-08-29T16:26:49","guid":{"rendered":"http:\/\/www.hazarapeople.com\/it\/?p=1419"},"modified":"2012-08-29T16:26:49","modified_gmt":"2012-08-29T16:26:49","slug":"minacce-di-morte-costringono-attrice-hazara-a-nascondersi","status":"publish","type":"post","link":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/","title":{"rendered":"Minacce di morte costringono attrice Hazara a nascondersi"},"content":{"rendered":"<p><strong>Tradotto da Lisa Maya Quaianni Manuzzato<\/strong><\/p>\n<figure id=\"attachment_1420\" aria-describedby=\"caption-attachment-1420\" style=\"width: 480px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2012\/08\/Sahar-Parnian-2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2012\/08\/Sahar-Parnian-2-e1346257338809.jpg\" alt=\"\" title=\"Sahar Parnian \" width=\"480\" height=\"320\" class=\"size-full wp-image-1420\" \/><\/a><figcaption id=\"caption-attachment-1420\" class=\"wp-caption-text\">Sahar Parniyan<\/figcaption><\/figure>\n<p><strong>Un\u2019attrice Hazara dell\u2019Afghanistan nota per il suo ruolo in una serie TV locale sulla corruzione e il sabotaggio si \u00e8 vista costretta a nascondersi dopo aver ricevuto minacce di morte. Secondo alcune sue dichiarazioni, sta vivendo in un incubo dopo che un\u2019amica attrice \u00e8 stata uccisa negli scorsi giorni, nell\u2019ultimo questo mese.<\/strong><\/p>\n<p>Sahar Parniyan \u00e8 apparsa frequentemente sullo schermo con la ventiduenne Benafsha, l\u2019artista uccisa. Si suppone che la promettente star sia stata assassinata a causa delle parti che recitava. I suoi ruoli erano considerati da alcuni contro i valori e la morale islamica. L\u2019attrice era stata oggetto di violenza verbale e di attacchi d\u2019odio quando era andata alla panetteria vicino a casa sua nella capitale afghana, Kabul.<\/p>\n<p><strong>Parniyan ha dichiarato che a seguito della morte di Benafsha anche lei ha ricevuto avvertimenti e che sar\u00e0 lei il prossimo target.<\/strong><a href=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2012\/08\/sahar-parnian.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2012\/08\/sahar-parnian-e1346257424730.jpg\" alt=\"\" title=\"sahar parnian\" width=\"480\" height=\"686\" class=\"aligncenter size-full wp-image-1421\" \/><\/a><\/p>\n<p>L\u2019attrice ha detto che si vedr\u00e0 costretta a tagliare l\u2019attivit\u00e0 filmica se le autorit\u00e0 non potessero garantirle sicurezza. La star cinematografica afferma che ha cambiato il suo indirizzo perch\u00e9 vivere a Kabul \u00e8 divenuto intollerabile per lei a seguito della morte della collega.<\/p>\n<p>Dopo la notizia dell\u2019assassinio di Benafsha, una schiera di fan della Parniayn ha scritto messaggi di supporto sulla sua pagina facebook. L\u2019attrice ha postato una risposta, dicendo che lei non ha lasciato l\u2019appartamento per stare in un posto sicuro.<\/p>\n<p><em><strong>Sono angosciata che ben prima del 2014, l\u2019estremismo, il terrore e il fondamentalismo sembrino incrementarsi talmente tanto da portar via le vite di artisti e attivisti della societ\u00e0 civile. La mia sola speranza \u00e8 Dio, i vostri incoraggiamenti e le vostre benedizioni e forse le guardie di sicurezza. D\u2019ora in poi sar\u00f2 costretta ad avere una scorta di sicurezza con me, del resto cosa posso fare, questa \u00e8 la situazione nel mio paese!\u201d<\/strong><\/em><\/p>\n<p>Fonte di notizia:Russia Today <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tradotto da Lisa Maya Quaianni Manuzzato Un\u2019attrice Hazara dell\u2019Afghanistan nota per il suo ruolo in una serie TV locale sulla corruzione e il sabotaggio si \u00e8 vista costretta a nascondersi dopo aver ricevuto minacce di morte. Secondo alcune sue dichiarazioni, sta vivendo in un incubo dopo che un\u2019amica attrice \u00e8 stata uccisa negli scorsi giorni, &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1421,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,12,1],"tags":[],"class_list":["post-1419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-afghanistan","category-diritti-delle-donne","category-hazara-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Minacce di morte costringono attrice Hazara a nascondersi - Rete Internazionale Hazara<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minacce di morte costringono attrice Hazara a nascondersi - Rete Internazionale Hazara\" \/>\n<meta property=\"og:description\" content=\"Tradotto da Lisa Maya Quaianni Manuzzato Un\u2019attrice Hazara dell\u2019Afghanistan nota per il suo ruolo in una serie TV locale sulla corruzione e il sabotaggio si \u00e8 vista costretta a nascondersi dopo aver ricevuto minacce di morte. Secondo alcune sue dichiarazioni, sta vivendo in un incubo dopo che un\u2019amica attrice \u00e8 stata uccisa negli scorsi giorni, &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rete Internazionale Hazara\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-29T16:26:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2012\/08\/sahar-parnian-e1346257424730.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amministratore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amministratore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/\"},\"author\":{\"name\":\"Amministratore\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\"},\"headline\":\"Minacce di morte costringono attrice Hazara a nascondersi\",\"datePublished\":\"2012-08-29T16:26:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/\"},\"wordCount\":330,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/sahar-parnian-e1346257424730.jpg\",\"articleSection\":[\"Afghanistan\",\"Diritti delle Donne\",\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/\",\"name\":\"Minacce di morte costringono attrice Hazara a nascondersi - Rete Internazionale Hazara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/sahar-parnian-e1346257424730.jpg\",\"datePublished\":\"2012-08-29T16:26:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/sahar-parnian-e1346257424730.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/sahar-parnian-e1346257424730.jpg\",\"width\":\"480\",\"height\":\"686\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minacce di morte costringono attrice Hazara a nascondersi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/\",\"name\":\"Rete Internazionale Hazara\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\",\"name\":\"Amministratore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"caption\":\"Amministratore\"},\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/author\\\/hazara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Minacce di morte costringono attrice Hazara a nascondersi - Rete Internazionale Hazara","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Minacce di morte costringono attrice Hazara a nascondersi - Rete Internazionale Hazara","og_description":"Tradotto da Lisa Maya Quaianni Manuzzato Un\u2019attrice Hazara dell\u2019Afghanistan nota per il suo ruolo in una serie TV locale sulla corruzione e il sabotaggio si \u00e8 vista costretta a nascondersi dopo aver ricevuto minacce di morte. Secondo alcune sue dichiarazioni, sta vivendo in un incubo dopo che un\u2019amica attrice \u00e8 stata uccisa negli scorsi giorni, &hellip;","og_url":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/","og_site_name":"Rete Internazionale Hazara","article_published_time":"2012-08-29T16:26:49+00:00","og_image":[{"width":480,"height":686,"url":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2012\/08\/sahar-parnian-e1346257424730.jpg","type":"image\/jpeg"}],"author":"Amministratore","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Amministratore","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/#article","isPartOf":{"@id":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/"},"author":{"name":"Amministratore","@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534"},"headline":"Minacce di morte costringono attrice Hazara a nascondersi","datePublished":"2012-08-29T16:26:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/"},"wordCount":330,"commentCount":0,"image":{"@id":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2012\/08\/sahar-parnian-e1346257424730.jpg","articleSection":["Afghanistan","Diritti delle Donne","News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/","url":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/","name":"Minacce di morte costringono attrice Hazara a nascondersi - Rete Internazionale Hazara","isPartOf":{"@id":"https:\/\/www.hazarainternational.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/#primaryimage"},"image":{"@id":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2012\/08\/sahar-parnian-e1346257424730.jpg","datePublished":"2012-08-29T16:26:49+00:00","author":{"@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534"},"breadcrumb":{"@id":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/#primaryimage","url":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2012\/08\/sahar-parnian-e1346257424730.jpg","contentUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2012\/08\/sahar-parnian-e1346257424730.jpg","width":"480","height":"686"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hazarainternational.com\/it\/minacce-di-morte-costringono-attrice-hazara-a-nascondersi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hazarainternational.com\/it\/"},{"@type":"ListItem","position":2,"name":"Minacce di morte costringono attrice Hazara a nascondersi"}]},{"@type":"WebSite","@id":"https:\/\/www.hazarainternational.com\/it\/#website","url":"https:\/\/www.hazarainternational.com\/it\/","name":"Rete Internazionale Hazara","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hazarainternational.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534","name":"Amministratore","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","caption":"Amministratore"},"url":"https:\/\/www.hazarainternational.com\/it\/author\/hazara\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/1419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/comments?post=1419"}],"version-history":[{"count":1,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/1419\/revisions"}],"predecessor-version":[{"id":1422,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/1419\/revisions\/1422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/media\/1421"}],"wp:attachment":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/media?parent=1419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/categories?post=1419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/tags?post=1419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}