{"id":1450,"date":"2013-01-05T00:22:14","date_gmt":"2013-01-05T00:22:14","guid":{"rendered":"http:\/\/www.hazarapeople.com\/it\/?p=1450"},"modified":"2013-01-05T00:27:38","modified_gmt":"2013-01-05T00:27:38","slug":"i-fichi-rossi-di-mazar-e-sharif","status":"publish","type":"post","link":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/","title":{"rendered":"I fichi rossi di Mazar-e Sharif"},"content":{"rendered":"<p><strong>Mohammad Hossein Mohammadi<\/p>\n<p>Una raccolta di racconti che sintetizza la cronaca di un conflitto interminabile che non ha risparmiato nessun angolo dell\u2019Afghanistan. Mohammad Hossein Mohammadi racconta con una scrittura semplice e intensa l\u2019orrore che la guerra ha portato fin dentro il cuore delle relazioni umane pi\u00f9 intime degli afghanistani. <\/strong><br \/>\n<a href=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2013\/01\/Mohammadi_copertina255x399.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2013\/01\/Mohammadi_copertina255x399-e1357345199799.jpg\" alt=\"Mohammadi_copertina255x399\" width=\"480\" height=\"670\" class=\"aligncenter size-full wp-image-1451\" \/><\/a><br \/>\nCronaca di un conflitto interminabile, i quattordici racconti de I fichi rossi di Mazar-e Sharif si trasformano, grazie alla scrittura lucida, elegante ed intensa di Mohammad Hossein Mohammadi, in una sinfonia di voci e di sentimenti sulle variazioni della guerra, la morte, l\u2019amore, la nostalgia per un Afghanistan perduto.<br \/>\nLa dolcezza del passato e l\u2019orrore di un lungo presente, simboleggiati dall\u2019albero di fichi del titolo che in un giardino di Mazar-e Sharif una bambina fruga alla ricerca di un frutto maturo, mentre il rombo degli aerei preannuncia morte e terrore, sono narrati attraverso una sapiente miscela di fantasia e realt\u00e0. <\/p>\n<p>Mohammadi, uno dei protagonisti della societ\u00e0 civile di un Paese che cerca disperatamente di ritrovare una propria strada verso la normalit\u00e0, ha scelto di far parlare tutti i protagonisti della tragedia corale nella quale l\u2019insensatezza della guerra ha gettato l\u2019Afghanistan: contadini uccisi mentre si apprestano a raccogliere il grano nell\u2019intervallo tra una battaglia e l\u2019altra; bambini che la guerra ha reso orfani, mutilati, segnati a fuoco dall\u2019orrore senza fine degli adulti; madri di famiglia costrette a prostituirsi nonostante l\u2019incubo della lapidazione; giovani fanciulle concupite come bottino di guerra; uomini normali che la guerra trasforma in mostri irsuti e insensibili; combattenti che scoprono le loro debolezze di uomini; difensori della libert\u00e0 che dimenticano il rispetto di valori che neanche la guerra dovrebbe calpestare.<\/p>\n<p> Mohammadi riserva ad ognuno di essi, anche a quei talebani esecrati dall\u2019Occidente e temuti in Afghanistan, uno sguardo che scandaglia i loro sentimenti pi\u00f9 profondi, e un posto nella Storia che la cronaca giornalistica ha spesso loro negato.<\/p>\n<p><a href=\"http:\/\/www.ponte33.it\/project\/index.php\/i-fichi-rossi-di-mazar-e-sharif\/\">fonte &#038; copyright<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mohammad Hossein Mohammadi Una raccolta di racconti che sintetizza la cronaca di un conflitto interminabile che non ha risparmiato nessun angolo dell\u2019Afghanistan. Mohammad Hossein Mohammadi racconta con una scrittura semplice e intensa l\u2019orrore che la guerra ha portato fin dentro il cuore delle relazioni umane pi\u00f9 intime degli afghanistani. Cronaca di un conflitto interminabile, i &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1451,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,5],"tags":[],"class_list":["post-1450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-europa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I fichi rossi di Mazar-e Sharif - Rete Internazionale Hazara<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I fichi rossi di Mazar-e Sharif - Rete Internazionale Hazara\" \/>\n<meta property=\"og:description\" content=\"Mohammad Hossein Mohammadi Una raccolta di racconti che sintetizza la cronaca di un conflitto interminabile che non ha risparmiato nessun angolo dell\u2019Afghanistan. Mohammad Hossein Mohammadi racconta con una scrittura semplice e intensa l\u2019orrore che la guerra ha portato fin dentro il cuore delle relazioni umane pi\u00f9 intime degli afghanistani. Cronaca di un conflitto interminabile, i &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/\" \/>\n<meta property=\"og:site_name\" content=\"Rete Internazionale Hazara\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-05T00:22:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-01-05T00:27:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2013\/01\/Mohammadi_copertina255x399-e1357345199799.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"255\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amministratore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amministratore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/\"},\"author\":{\"name\":\"Amministratore\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\"},\"headline\":\"I fichi rossi di Mazar-e Sharif\",\"datePublished\":\"2013-01-05T00:22:14+00:00\",\"dateModified\":\"2013-01-05T00:27:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/\"},\"wordCount\":329,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/Mohammadi_copertina255x399-e1357345199799.jpg\",\"articleSection\":[\"Arte\",\"Europa\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/\",\"name\":\"I fichi rossi di Mazar-e Sharif - Rete Internazionale Hazara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/Mohammadi_copertina255x399-e1357345199799.jpg\",\"datePublished\":\"2013-01-05T00:22:14+00:00\",\"dateModified\":\"2013-01-05T00:27:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/Mohammadi_copertina255x399-e1357345199799.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/Mohammadi_copertina255x399-e1357345199799.jpg\",\"width\":255,\"height\":399},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/i-fichi-rossi-di-mazar-e-sharif\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I fichi rossi di Mazar-e Sharif\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/\",\"name\":\"Rete Internazionale Hazara\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\",\"name\":\"Amministratore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"caption\":\"Amministratore\"},\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/author\\\/hazara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I fichi rossi di Mazar-e Sharif - Rete Internazionale Hazara","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"I fichi rossi di Mazar-e Sharif - Rete Internazionale Hazara","og_description":"Mohammad Hossein Mohammadi Una raccolta di racconti che sintetizza la cronaca di un conflitto interminabile che non ha risparmiato nessun angolo dell\u2019Afghanistan. Mohammad Hossein Mohammadi racconta con una scrittura semplice e intensa l\u2019orrore che la guerra ha portato fin dentro il cuore delle relazioni umane pi\u00f9 intime degli afghanistani. Cronaca di un conflitto interminabile, i &hellip;","og_url":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/","og_site_name":"Rete Internazionale Hazara","article_published_time":"2013-01-05T00:22:14+00:00","article_modified_time":"2013-01-05T00:27:38+00:00","og_image":[{"width":255,"height":399,"url":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2013\/01\/Mohammadi_copertina255x399-e1357345199799.jpg","type":"image\/jpeg"}],"author":"Amministratore","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Amministratore","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/#article","isPartOf":{"@id":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/"},"author":{"name":"Amministratore","@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534"},"headline":"I fichi rossi di Mazar-e Sharif","datePublished":"2013-01-05T00:22:14+00:00","dateModified":"2013-01-05T00:27:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/"},"wordCount":329,"commentCount":1,"image":{"@id":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2013\/01\/Mohammadi_copertina255x399-e1357345199799.jpg","articleSection":["Arte","Europa"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/","url":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/","name":"I fichi rossi di Mazar-e Sharif - Rete Internazionale Hazara","isPartOf":{"@id":"https:\/\/www.hazarainternational.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/#primaryimage"},"image":{"@id":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2013\/01\/Mohammadi_copertina255x399-e1357345199799.jpg","datePublished":"2013-01-05T00:22:14+00:00","dateModified":"2013-01-05T00:27:38+00:00","author":{"@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534"},"breadcrumb":{"@id":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/#primaryimage","url":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2013\/01\/Mohammadi_copertina255x399-e1357345199799.jpg","contentUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2013\/01\/Mohammadi_copertina255x399-e1357345199799.jpg","width":255,"height":399},{"@type":"BreadcrumbList","@id":"https:\/\/www.hazarainternational.com\/it\/i-fichi-rossi-di-mazar-e-sharif\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hazarainternational.com\/it\/"},{"@type":"ListItem","position":2,"name":"I fichi rossi di Mazar-e Sharif"}]},{"@type":"WebSite","@id":"https:\/\/www.hazarainternational.com\/it\/#website","url":"https:\/\/www.hazarainternational.com\/it\/","name":"Rete Internazionale Hazara","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hazarainternational.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534","name":"Amministratore","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","caption":"Amministratore"},"url":"https:\/\/www.hazarainternational.com\/it\/author\/hazara\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/1450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/comments?post=1450"}],"version-history":[{"count":2,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/1450\/revisions"}],"predecessor-version":[{"id":1453,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/1450\/revisions\/1453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/media\/1451"}],"wp:attachment":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/media?parent=1450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/categories?post=1450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/tags?post=1450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}