{"id":151,"date":"2011-08-11T17:36:40","date_gmt":"2011-08-11T17:36:40","guid":{"rendered":"http:\/\/www.hazarapeople.com\/it\/?p=151"},"modified":"2011-10-27T21:57:23","modified_gmt":"2011-10-27T21:57:23","slug":"afghanistan-2014","status":"publish","type":"post","link":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/","title":{"rendered":"Afghanistan 2014"},"content":{"rendered":"<p><strong>di Razi e Soheila Mohebi<\/strong><\/p>\n<p><strong>Il 15 febbraio 1989 Boris Vsevolodovich Gromov, generale a capo dell&#8217;Armata Rossa, attraversa il ponte sul fiume Amu-Daria, al confine fra l\u2019Afghanistan e l\u2019ex Unione Sovietica. Giunto alla met\u00e0 di quello che veniva chiamato \u201cponte dell\u2019amicizia\u201d, si ferma e si volta indietro. Gettando lo sguardo sul paese che il suo esercito abbandonava dopo 10 anni, mormora fra s\u00e9 e s\u00e9 alcune parole. Nessuno ha mai saputo il contenuto di queste parole sussurrate&#8230; forse una preghiera per i suoi soldati caduti in una guerra senza senso, forse un sospiro di sollievo per essere uscito vivo dalla \u201c\u2019palude afghana\u2019\u201d.<\/strong><br \/>\n<a href=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2011\/08\/esercito-russo-in-afg.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2011\/08\/esercito-russo-in-afg-e1312891584359.jpg\" alt=\"\" title=\"esercito russo in afg\" width=\"480\" height=\"319\" class=\"aligncenter size-full wp-image-152\" \/><\/a><br \/>\nForse ancora l\u2019invocazione di una illusoria giustizia storica: gli americani, che avevano appoggiato le milizie in rivolta, avrebbero vissuto un giorno la stessa sconfitta.<\/p>\n<p>A 22 anni di distanza da quella data, le misteriose parole che molti libri di storia hanno messo in bocca al generale russo suggeriscono una riflessione. La storia, come prevedibile, si e\u2019 ripetuta. Ai dieci anni della dominazione sovietica si sono aggiunti oggi i dieci di quella internazionale, a guida americana. Nel luglio 2011 i primi soldati americani hanno iniziato a ritirarsi dal paese, preannunciando una \u201c\u2019strategia di uscita\u2019\u201d destinata a avere il culmine nel 2014.<br \/>\n<a href=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186-e1312891641525.jpg\" alt=\"\" title=\"SONY DSC\" width=\"480\" height=\"321\" class=\"aligncenter size-full wp-image-153\" srcset=\"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186-e1312891641525.jpg 480w, https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186-e1312891641525-165x110.jpg 165w, https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186-e1312891641525-270x180.jpg 270w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><br \/>\nLa guerra estenuante contro i sovietici aveva lasciato in eredit\u00e0 agli afghani un paese profondamente diviso, che nel 1989 precipiter\u00e0 in una lunga guerra civile, proseguita fino al 2001. Anche questi \u201ceffetti collaterali\u201d si ripeteranno dopo il prossimo ritiro? Questo interrogativo preoccupa quanti, afghani e non, hanno a cuore il futuro dell\u2019Afghanistan, all\u2019interno del paese e nel mondo. Guardandoci negli occhi, leggiamo una preoccupazione che ha radici lontane.<\/p>\n<p>A preoccupare sono piu\u2019 elementi. Rispetto al 1989, la situazione appare pi\u00f9 difficile e complessa: l\u2019esercito afghano, ricostruito da zero negli ultimi anni, \u00e9 poco preparato e male equipaggiato; le istituzioni pubbliche hanno una scarsa legittimit\u00e0 e l\u2019economia \u00e9 drogata dalla guerra, dal commercio dell\u2019oppio e da una corruzione capillare. Tutto questo rende ulteriormente fragile il tessuto sociale, e fa presagire scenari di conflitto etnico che potrebbero sfociare in una nuova guerra civile. <\/p>\n<p><strong>Negli ultimi mesi inoltre le notizie delle trattative fra Stati Uniti e leader talebani corrispondono ad un tentativo di riabilitare l\u2019immagine pubblica di questi ultimi, revisione che potrebbe preparare il terreno a accordi calati dall\u2019alto e lontani dalle necessit\u00e0 della popolazione. L\u2019interrogativo su ci\u00f2 che succeder\u00e0 dopo il 2014 diventa pertanto ancora pi\u00f9 necessario e urgente.<br \/>\n<\/strong><br \/>\nNel guardare al futuro dell\u2019Afghanistan vediamo un vuoto: da una parte, le rivendicazioni politiche e sociali dei movimenti che hanno dominato il paese si sono finora ispirate a teorie importate dall\u2019estero, confinando allo spazio dell\u2019oralit\u00e0 la trasmissione di una coscienza nazionale. Dall\u2019altra l\u2019opinione pubblica occidentale appare spesso influenzata da visioni stereotipate e semplicistiche.<\/p>\n<p><strong>Afghanistan 2014 nasce come un tentativo di colmare questo vuoto, creando uno spazio di dialogo e confronto tra intellettuali, artisti, giornalisti, ricercatori, attivisti e studenti afghani e non.<br \/>\nVogliamo documentare e mettere su carta proposte, interpretazioni, visioni, teorie e punti di vista su \u201cAfghanistan 2014\u201d, per trovarne i punti comuni e individuare i semi di possibili soluzioni. <\/strong><\/p>\n<p>Occorre a nostro avviso gettare le basi di una diplomazia popolare, stimolando la capacita da parte della societ\u00e0 civile afghana ed occidentale di elaborare riflessioni e soluzioni. Indagare la storia e la memoria, e le loro narrazioni, per trovare gli elementi di una narrazione condivisa e di un dibattito fecondo.<br \/>\n<a href=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2011\/08\/americani-inafg.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2011\/08\/americani-inafg-e1312891730201.jpg\" alt=\"\" title=\"americani inafg\" width=\"480\" height=\"359\" class=\"aligncenter size-full wp-image-154\" \/><\/a><br \/>\nI mezzi sono a disposizione di tutti nella quotidianit\u00e0. Innanzitutto quelli offerti dalle nuove tecnologie della rete internet, che intendiamo sfruttare per creare spazi di condivisione e dialogo, quindi l\u2019incontro diretto tramite conferenze, incontri pubblici, scambi e gemellaggi fra universit\u00e0 e centri culturali e infine la pubblicazione e la circolazione di opere scritte e di realizzazioni cinematografiche in Afghanistan e nel mondo occidentale.<\/p>\n<p>Afghanistan 2014 vuole dunque porsi come punto di raccordo fra soggetti diversi, come centro di raccolta di articoli e espressioni culturali e artistiche e come osservatorio sull\u2019andamento della \u201cquestione afghana\u201d nei tre anni che ci separano dal 2014.<\/p>\n<p><strong>Il 13 luglio 2011 i primi soldati del contingente americano sono partiti, dando il via a un lungo ritiro. Nel dicembre 2014, mentre i festeggiamenti esploderanno nelle strade del paese, l\u2019ultimo militare della coalizione N.A.T.O. osserver\u00e0 l\u2019Afghanistan dall\u2019alto, chiuso nell\u2019abitacolo di un aereo ultraveloce.<\/strong><\/p>\n<p>In questi tre anni vogliamo abbassare lo sguardo: dal livello della forza e della diplomazia internazionale a quello delle persone, delle idee e dell\u2019azione sociale. Vogliamo salire su un\u2019ideale \u201cponte dell\u2019amicizia\u201d costruito da conoscenze, incontri e proposte. Girarci, una volta arrivati a met\u00e0, e poter pronunciare parole chiare, capaci di arrivare lontano e di costruire nuovi ponti.<\/p>\n<p>Guardarci negli occhi con franchezza, per lasciare al passato parole perse nel vento e sguardi distratti.<\/p>\n<p><strong>Razi e Soheila Mohebi, registi Hazara rifugiati in Italia.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Razi e Soheila Mohebi Il 15 febbraio 1989 Boris Vsevolodovich Gromov, generale a capo dell&#8217;Armata Rossa, attraversa il ponte sul fiume Amu-Daria, al confine fra l\u2019Afghanistan e l\u2019ex Unione Sovietica. Giunto alla met\u00e0 di quello che veniva chiamato \u201cponte dell\u2019amicizia\u201d, si ferma e si volta indietro. Gettando lo sguardo sul paese che il suo &hellip;<\/p>\n","protected":false},"author":2,"featured_media":153,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[],"class_list":["post-151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-afghanistan","category-europa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Afghanistan 2014 - Rete Internazionale Hazara<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afghanistan 2014 - Rete Internazionale Hazara\" \/>\n<meta property=\"og:description\" content=\"di Razi e Soheila Mohebi Il 15 febbraio 1989 Boris Vsevolodovich Gromov, generale a capo dell&#8217;Armata Rossa, attraversa il ponte sul fiume Amu-Daria, al confine fra l\u2019Afghanistan e l\u2019ex Unione Sovietica. Giunto alla met\u00e0 di quello che veniva chiamato \u201cponte dell\u2019amicizia\u201d, si ferma e si volta indietro. Gettando lo sguardo sul paese che il suo &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/\" \/>\n<meta property=\"og:site_name\" content=\"Rete Internazionale Hazara\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-11T17:36:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-10-27T21:57:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186-e1312891641525.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"321\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amministratore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amministratore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/\"},\"author\":{\"name\":\"Amministratore\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\"},\"headline\":\"Afghanistan 2014\",\"datePublished\":\"2011-08-11T17:36:40+00:00\",\"dateModified\":\"2011-10-27T21:57:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/\"},\"wordCount\":798,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/DSC00186-e1312891641525.jpg\",\"articleSection\":[\"Afghanistan\",\"Europa\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/\",\"name\":\"Afghanistan 2014 - Rete Internazionale Hazara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/DSC00186-e1312891641525.jpg\",\"datePublished\":\"2011-08-11T17:36:40+00:00\",\"dateModified\":\"2011-10-27T21:57:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/DSC00186-e1312891641525.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/DSC00186-e1312891641525.jpg\",\"width\":\"480\",\"height\":\"321\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/afghanistan-2014\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Afghanistan 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/\",\"name\":\"Rete Internazionale Hazara\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\",\"name\":\"Amministratore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"caption\":\"Amministratore\"},\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/author\\\/hazara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Afghanistan 2014 - Rete Internazionale Hazara","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Afghanistan 2014 - Rete Internazionale Hazara","og_description":"di Razi e Soheila Mohebi Il 15 febbraio 1989 Boris Vsevolodovich Gromov, generale a capo dell&#8217;Armata Rossa, attraversa il ponte sul fiume Amu-Daria, al confine fra l\u2019Afghanistan e l\u2019ex Unione Sovietica. Giunto alla met\u00e0 di quello che veniva chiamato \u201cponte dell\u2019amicizia\u201d, si ferma e si volta indietro. Gettando lo sguardo sul paese che il suo &hellip;","og_url":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/","og_site_name":"Rete Internazionale Hazara","article_published_time":"2011-08-11T17:36:40+00:00","article_modified_time":"2011-10-27T21:57:23+00:00","og_image":[{"width":480,"height":321,"url":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186-e1312891641525.jpg","type":"image\/jpeg"}],"author":"Amministratore","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Amministratore","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/#article","isPartOf":{"@id":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/"},"author":{"name":"Amministratore","@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534"},"headline":"Afghanistan 2014","datePublished":"2011-08-11T17:36:40+00:00","dateModified":"2011-10-27T21:57:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/"},"wordCount":798,"commentCount":0,"image":{"@id":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186-e1312891641525.jpg","articleSection":["Afghanistan","Europa"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/","url":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/","name":"Afghanistan 2014 - Rete Internazionale Hazara","isPartOf":{"@id":"https:\/\/www.hazarainternational.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/#primaryimage"},"image":{"@id":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186-e1312891641525.jpg","datePublished":"2011-08-11T17:36:40+00:00","dateModified":"2011-10-27T21:57:23+00:00","author":{"@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534"},"breadcrumb":{"@id":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/#primaryimage","url":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186-e1312891641525.jpg","contentUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/DSC00186-e1312891641525.jpg","width":"480","height":"321"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hazarainternational.com\/it\/afghanistan-2014\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hazarainternational.com\/it\/"},{"@type":"ListItem","position":2,"name":"Afghanistan 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.hazarainternational.com\/it\/#website","url":"https:\/\/www.hazarainternational.com\/it\/","name":"Rete Internazionale Hazara","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hazarainternational.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534","name":"Amministratore","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","caption":"Amministratore"},"url":"https:\/\/www.hazarainternational.com\/it\/author\/hazara\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/comments?post=151"}],"version-history":[{"count":6,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/151\/revisions"}],"predecessor-version":[{"id":569,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/151\/revisions\/569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/media\/153"}],"wp:attachment":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/media?parent=151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/categories?post=151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/tags?post=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}