{"id":409,"date":"2011-08-24T06:42:03","date_gmt":"2011-08-24T06:42:03","guid":{"rendered":"http:\/\/www.hazarapeople.com\/it\/?p=409"},"modified":"2011-08-24T06:44:20","modified_gmt":"2011-08-24T06:44:20","slug":"shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara","status":"publish","type":"post","link":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/","title":{"rendered":"SHAHADA il film di Burhan Qurbani, il giovane regista Hazara"},"content":{"rendered":"<p><strong>Berlino<\/strong> &#8211; Sono passati molti anni da quando uno studente tedesco ha girato un lungometraggio finito poi in gara al prestigioso Festival Internazionale del Cinema di Berlino, un riconoscimento questo che pu\u00f2 essere il trampolino di lancio per una grande carriera. Tutto ci\u00f2 si sta godendo in questo momento Burhan Qurbani il giovane regista Hazara con il suo film \u201cShahada\u201d.<br \/>\n<figure id=\"attachment_410\" aria-describedby=\"caption-attachment-410\" style=\"width: 480px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2011\/08\/GERMANY-2-articleLarge.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.hazarapeople.com\/it\/wp-content\/uploads\/2011\/08\/GERMANY-2-articleLarge-e1314167962512.jpg\" alt=\"\" title=\"Burhan Qurbani\" width=\"480\" height=\"280\" class=\"size-full wp-image-410\" \/><\/a><figcaption id=\"caption-attachment-410\" class=\"wp-caption-text\">Burhan Qurbani Regista di &quot;SHAHADA&quot;<\/figcaption><\/figure><br \/>\nMa la fama nascente pu\u00f2 avere un risvolto della medaglia, e lo sta sperimentando Qurbani, dal momento che il suo paese nat\u00eco ha un occhio critico nei confronti del suo lavoro e della sua vita. Si \u00e8 improvvisamente reso conto di essere uno straniero nella propria patria, e che per un certo pubblico lui \u00e8 un immigrato afgano che ha girato un film sull\u2019islam e non un talentuoso regista tedesco che ha scelto di affrontare problematiche comuni a tutta la razza umana.<\/p>\n<p><strong>\u201cSono visto come l\u2019afgano che ha fatto un film sull\u2019integrazione, e questo mi d\u00e0 un po\u2019 fastidio\u201d,ha dichiarato qualche giorno fa, sedendo in  un caff\u00e8 all\u2019aperto e fumando una sigaretta rollata a mano dopo l\u2019altra.<\/strong><\/p>\n<p>I personaggi del film, tre giovani musulmani che vivono a Berlino, si scontrano con problemi come l\u2019amore proibito e il senso di colpa e cercano riparo e redenzione nella religione. Ma  \u00e8 il contesto ci\u00f2 che realmente definisce in film, e in particolare questo film, che \u00e8 stato prodotto nel 2009 ma fatto uscire solo quest\u2019anno in mezzo a dibattiti sull\u2019integrazione e crescenti sentimenti anti islamici in tutta la Germania.<\/p>\n<p><strong>\u201cCerto che sono tedesco\u201dha dichiarato Qurbani.\u201dHo radici Afgane, non lo posso negare, ma sono principalmente tedesco\u201d.<\/strong><br \/>\n<iframe loading=\"lazy\" width=\"480\" height=\"345\" src=\"http:\/\/www.youtube.com\/embed\/e_8O5RWiJfQ\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>La storia di Qurbani \u00e8 la favola di un immigrato di successo. I suoi gentori fuggirono dall\u2019invasione sovietica dell\u2019Afghanistan e si stabilirono in Germania.Suo padre era un elettricista, ma i suoi genitori divorziarono, cos\u00ec sua madre allev\u00f2 da sola due ragazzi con l\u2019aiuto della pubblica assistenza. Egli ricevette un\u2019educazione di prim\u2019ordine e la possibilit\u00e0 di seguire il suo sogno di diventare un regista.<\/p>\n<p>\u201cShahada\u201d, il suo primo lungometraggio nonch\u00e9 la sua tesi di laurea, \u00e8 stato proiettata al Festival di Berlino in febbraio e nei cinema berlinesi nelle ultime due settimane. Sabato sera il Chicago International Film Festival ha insignito Qurbani della medaglia doro per il miglior regista emergente per \u201cShahada\u201d.<\/p>\n<p>\u201cIn un mondo fatto di narrazioni che che si sovrappongono, \u201cShahada\u201d localizza precisamente i punti di forza nelle complicate vite dei suoi personaggi &#8211; lavoro e amore,immigrazione e Islam\u201d, diceva la dichiarazione di apertura della premiazione.\u201dLa storia si svolge nella Germania ed Europa di oggi, ma le sue implicazioni sono universali\u201d.<\/p>\n<p><a href=\"http:\/\/www.nytimes.com\/2010\/10\/18\/world\/europe\/18germany.html\">Fonte<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berlino &#8211; Sono passati molti anni da quando uno studente tedesco ha girato un lungometraggio finito poi in gara al prestigioso Festival Internazionale del Cinema di Berlino, un riconoscimento questo che pu\u00f2 essere il trampolino di lancio per una grande carriera. Tutto ci\u00f2 si sta godendo in questo momento Burhan Qurbani il giovane regista Hazara &hellip;<\/p>\n","protected":false},"author":2,"featured_media":410,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,5,1,22],"tags":[],"class_list":["post-409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-europa","category-hazara-news","category-popolazione-hazara"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SHAHADA il film di Burhan Qurbani, il giovane regista Hazara - Rete Internazionale Hazara<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SHAHADA il film di Burhan Qurbani, il giovane regista Hazara - Rete Internazionale Hazara\" \/>\n<meta property=\"og:description\" content=\"Berlino &#8211; Sono passati molti anni da quando uno studente tedesco ha girato un lungometraggio finito poi in gara al prestigioso Festival Internazionale del Cinema di Berlino, un riconoscimento questo che pu\u00f2 essere il trampolino di lancio per una grande carriera. Tutto ci\u00f2 si sta godendo in questo momento Burhan Qurbani il giovane regista Hazara &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/\" \/>\n<meta property=\"og:site_name\" content=\"Rete Internazionale Hazara\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-24T06:42:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-08-24T06:44:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/GERMANY-2-articleLarge-e1314167962512.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amministratore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amministratore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/\"},\"author\":{\"name\":\"Amministratore\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\"},\"headline\":\"SHAHADA il film di Burhan Qurbani, il giovane regista Hazara\",\"datePublished\":\"2011-08-24T06:42:03+00:00\",\"dateModified\":\"2011-08-24T06:44:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/\"},\"wordCount\":464,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/GERMANY-2-articleLarge-e1314167962512.jpg\",\"articleSection\":[\"Arte\",\"Europa\",\"News\",\"Popolazione Hazara\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/\",\"name\":\"SHAHADA il film di Burhan Qurbani, il giovane regista Hazara - Rete Internazionale Hazara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/GERMANY-2-articleLarge-e1314167962512.jpg\",\"datePublished\":\"2011-08-24T06:42:03+00:00\",\"dateModified\":\"2011-08-24T06:44:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/GERMANY-2-articleLarge-e1314167962512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/GERMANY-2-articleLarge-e1314167962512.jpg\",\"width\":\"480\",\"height\":\"280\",\"caption\":\"Burhan Qurbani Regista di \\\"SHAHADA\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SHAHADA il film di Burhan Qurbani, il giovane regista Hazara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/\",\"name\":\"Rete Internazionale Hazara\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/#\\\/schema\\\/person\\\/9944aab83805cd99b9f3342cbe22c534\",\"name\":\"Amministratore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g\",\"caption\":\"Amministratore\"},\"url\":\"https:\\\/\\\/www.hazarainternational.com\\\/it\\\/author\\\/hazara\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SHAHADA il film di Burhan Qurbani, il giovane regista Hazara - Rete Internazionale Hazara","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"SHAHADA il film di Burhan Qurbani, il giovane regista Hazara - Rete Internazionale Hazara","og_description":"Berlino &#8211; Sono passati molti anni da quando uno studente tedesco ha girato un lungometraggio finito poi in gara al prestigioso Festival Internazionale del Cinema di Berlino, un riconoscimento questo che pu\u00f2 essere il trampolino di lancio per una grande carriera. Tutto ci\u00f2 si sta godendo in questo momento Burhan Qurbani il giovane regista Hazara &hellip;","og_url":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/","og_site_name":"Rete Internazionale Hazara","article_published_time":"2011-08-24T06:42:03+00:00","article_modified_time":"2011-08-24T06:44:20+00:00","og_image":[{"width":480,"height":280,"url":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/GERMANY-2-articleLarge-e1314167962512.jpg","type":"image\/jpeg"}],"author":"Amministratore","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Amministratore","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/#article","isPartOf":{"@id":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/"},"author":{"name":"Amministratore","@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534"},"headline":"SHAHADA il film di Burhan Qurbani, il giovane regista Hazara","datePublished":"2011-08-24T06:42:03+00:00","dateModified":"2011-08-24T06:44:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/"},"wordCount":464,"commentCount":0,"image":{"@id":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/GERMANY-2-articleLarge-e1314167962512.jpg","articleSection":["Arte","Europa","News","Popolazione Hazara"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/","url":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/","name":"SHAHADA il film di Burhan Qurbani, il giovane regista Hazara - Rete Internazionale Hazara","isPartOf":{"@id":"https:\/\/www.hazarainternational.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/#primaryimage"},"image":{"@id":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/GERMANY-2-articleLarge-e1314167962512.jpg","datePublished":"2011-08-24T06:42:03+00:00","dateModified":"2011-08-24T06:44:20+00:00","author":{"@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534"},"breadcrumb":{"@id":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/#primaryimage","url":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/GERMANY-2-articleLarge-e1314167962512.jpg","contentUrl":"https:\/\/www.hazarainternational.com\/it\/wp-content\/uploads\/2011\/08\/GERMANY-2-articleLarge-e1314167962512.jpg","width":"480","height":"280","caption":"Burhan Qurbani Regista di \"SHAHADA\""},{"@type":"BreadcrumbList","@id":"https:\/\/www.hazarainternational.com\/it\/shahada-il-film-di-burhan-qurbani-il-giovane-regista-hazara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hazarainternational.com\/it\/"},{"@type":"ListItem","position":2,"name":"SHAHADA il film di Burhan Qurbani, il giovane regista Hazara"}]},{"@type":"WebSite","@id":"https:\/\/www.hazarainternational.com\/it\/#website","url":"https:\/\/www.hazarainternational.com\/it\/","name":"Rete Internazionale Hazara","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hazarainternational.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.hazarainternational.com\/it\/#\/schema\/person\/9944aab83805cd99b9f3342cbe22c534","name":"Amministratore","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f6c77374a53d1ddcde50c8d2225fe684cc1572fd6e6dc4da2f48517a340412a?s=96&d=mm&r=g","caption":"Amministratore"},"url":"https:\/\/www.hazarainternational.com\/it\/author\/hazara\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/comments?post=409"}],"version-history":[{"count":3,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/409\/revisions"}],"predecessor-version":[{"id":412,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/posts\/409\/revisions\/412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/media\/410"}],"wp:attachment":[{"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/media?parent=409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/categories?post=409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hazarainternational.com\/it\/wp-json\/wp\/v2\/tags?post=409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}